{"id":6676,"date":"2021-08-25T17:28:17","date_gmt":"2021-08-25T17:28:17","guid":{"rendered":"https:\/\/www.dinamicaballet.com\/?page_id=6676"},"modified":"2025-11-06T12:10:53","modified_gmt":"2025-11-06T11:10:53","slug":"barra-de-ballet-mobil-doble-daltura-regulable-giselle","status":"publish","type":"page","link":"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/","title":{"rendered":"Giselle, barra de ballet m\u00f2bil doble d&#8217;altura regulable"},"content":{"rendered":"\n<div class=\"wp-block-genesis-blocks-gb-container gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<p><a href=\"https:\/\/www.dinamicaballet.com\/ca\/productes\/\" class=\"ek-link\"><\/a><a href=\"https:\/\/www.dinamicaballet.com\/ca\/productes\/\" class=\"ek-link\">Productes<\/a><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barres-de-ballet-mobils\/\" class=\"ek-link\">&nbsp;\/&nbsp;Barres de ballet m\u00f2bils<\/a><\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Giselle, barra de ballet m\u00f2bil doble d&#8217;altura regulable<\/h1>\n\n\n<style>.kb-row-layout-id6676_4e2dc3-33 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6676_4e2dc3-33 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6676_4e2dc3-33 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(65% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(35% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id6676_4e2dc3-33 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6676_4e2dc3-33 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6676_4e2dc3-33 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6676_4e2dc3-33 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6676_41eb07-19 > .kt-inside-inner-col,.kadence-column6676_41eb07-19 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_41eb07-19 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_41eb07-19 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_41eb07-19 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_41eb07-19 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_41eb07-19{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_41eb07-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_41eb07-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_41eb07-19 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<p>La Giselle \u00e9s una barra de ballet professional amb suports per a dues barres de fusta i mecanisme de regulaci\u00f3 que et permet treballar amb un rang d&#8217;altures de 70 cent\u00edmetres fins als 120 cent\u00edmetres. Hem dissenyat aquesta barra per a un \u00fas professional intensiu amb ballarines i esportistes de qualsevol edat i al\u00e7ada. Amb dos tipus de base a triar, amb rodes o plana, podr\u00e0s traslladar la barra de ballet entre classes amb gran facilitat.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column6676_1e07f1-ec > .kt-inside-inner-col,.kadence-column6676_1e07f1-ec > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_1e07f1-ec > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_1e07f1-ec > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_1e07f1-ec > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_1e07f1-ec > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_1e07f1-ec{text-align:right;}.kadence-column6676_1e07f1-ec{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_1e07f1-ec > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_1e07f1-ec > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_1e07f1-ec inner-column-2\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-buttons is-horizontal is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-ae2fe186 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button button_blue\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.dinamicaballet.com\/ca\/producto\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/\">Comprar a <strong>botiga online<\/strong><\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-6676_08d8fd-9e{padding-bottom:60px;}.kb-gallery-id-6676_08d8fd-9e .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-6676_08d8fd-9e .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-6676_08d8fd-9e.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-6676_08d8fd-9e.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;}.kb-gallery-id-6676_08d8fd-9e .splide.kt-carousel-dotstyle-outlinedark .splide__pagination__page{background-color:transparent;box-shadow:inset 0 0 0 1px #000;-webkit-transition:box-shadow 0.3s ease;-moz-transition:box-shadow 0.3s ease;transition:box-shadow 0.3s ease;}.kb-gallery-id-6676_08d8fd-9e .splide.kt-carousel-dotstyle-outlinedark .splide__pagination__page.is-active{background-color:transparent;box-shadow:inset 0 0 0 8px #000;}<\/style><div class=\"kb-gallery-wrap-id-6676_08d8fd-9e alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-slider kb-gallery-id-6676_08d8fd-9e kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel splide kt-carousel-container-dotstyle-outlinedark kt-carousel-arrowstyle-none kt-carousel-dotstyle-outlinedark kb-slider-group-arrow kb-slider-arrow-position-center\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"true\" data-slider-type=\"slider\" data-slider-hover-pause=\"false\" data-slider-auto=\"1\" data-slider-speed=\"7000\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"kt-blocks-carousel-init kb-blocks-slider splide__list\"><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-scaled.jpg\" width=\"2560\" height=\"1191\" alt=\"Barra de ballet doble de altura regulable Giselle\" data-full-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-scaled.jpg\" data-light-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-scaled.jpg\" data-id=\"1795\" class=\"wp-image-1795 skip-lazy\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-scaled.jpg 2560w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-300x140.jpg 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-1024x476.jpg 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-768x357.jpg 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-1536x714.jpg 1536w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-2048x953.jpg 2048w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-1200x558.jpg 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-1400x651.jpg 1400w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_slider_03_dinamica_ballet-600x279.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-scaled.jpg\" width=\"2560\" height=\"1191\" alt=\"Barra de ballet m\u00f3vil doble de altura regulable Giselle\" data-full-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-scaled.jpg\" data-light-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-scaled.jpg\" data-id=\"2974\" class=\"wp-image-2974 skip-lazy\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-scaled.jpg 2560w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-300x140.jpg 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-1024x476.jpg 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-768x357.jpg 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-1536x714.jpg 1536w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-2048x953.jpg 2048w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-1200x558.jpg 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-1400x651.jpg 1400w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/giselle_slider_02_dinamica_ballet-600x279.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01.webp\" width=\"2560\" height=\"1707\" alt=\"Barra de ballet m\u00f3vil doble de altura regulable Giselle\" data-full-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01.webp\" data-light-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01.webp\" data-id=\"105117\" class=\"wp-image-105117 skip-lazy\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01.webp 2560w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-300x200.webp 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-1024x683.webp 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-768x512.webp 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-1536x1024.webp 1536w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-2048x1366.webp 2048w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-1200x800.webp 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-600x400.webp 600w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-1400x934.webp 1400w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-500x333.webp 500w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-800x533.webp 800w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-1280x854.webp 1280w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_01-1920x1280.webp 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-scaled.webp\" width=\"2560\" height=\"1707\" alt=\"Barra de ballet doble de altura regulable Giselle\" data-full-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-scaled.webp\" data-light-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-scaled.webp\" data-id=\"105028\" class=\"wp-image-105028 skip-lazy\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-scaled.webp 2560w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-300x200.webp 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-1024x683.webp 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-768x512.webp 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-1536x1024.webp 1536w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-2048x1365.webp 2048w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-1200x800.webp 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-600x400.webp 600w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-1400x933.webp 1400w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-500x333.webp 500w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-800x533.webp 800w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-1280x853.webp 1280w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_01-1920x1280.webp 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02.webp\" width=\"2560\" height=\"1707\" alt=\"Barra de ballet doble de altura regulable Giselle\" data-full-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02.webp\" data-light-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02.webp\" data-id=\"105124\" class=\"wp-image-105124 skip-lazy\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02.webp 2560w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-300x200.webp 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-1024x683.webp 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-768x512.webp 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-1536x1024.webp 1536w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-2048x1366.webp 2048w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-1200x800.webp 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-600x400.webp 600w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-1400x934.webp 1400w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-500x333.webp 500w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-800x533.webp 800w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-1280x854.webp 1280w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_giselle_slider_02-1920x1280.webp 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-scaled.webp\" width=\"2560\" height=\"1707\" alt=\"Barra de ballet doble de altura regulable Giselle\" data-full-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-scaled.webp\" data-light-image=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-scaled.webp\" data-id=\"105034\" class=\"wp-image-105034 skip-lazy\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-scaled.webp 2560w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-300x200.webp 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-1024x683.webp 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-768x512.webp 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-1536x1024.webp 1536w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-2048x1365.webp 2048w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-1200x800.webp 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-600x400.webp 600w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-1400x933.webp 1400w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-500x333.webp 500w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-800x533.webp 800w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-1280x853.webp 1280w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2025\/11\/dinamica_ballet_slider_giselle_02-1920x1280.webp 1920w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\n\n<style>.kb-row-layout-id6676_4fd4d5-2f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6676_4fd4d5-2f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6676_4fd4d5-2f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-right:0px;padding-bottom:25px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id6676_4fd4d5-2f > .kt-row-layout-overlay{opacity:0.00;background-color:#cff0f5;}@media all and (max-width: 1024px){.kb-row-layout-id6676_4fd4d5-2f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6676_4fd4d5-2f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6676_4fd4d5-2f alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6676_80a5e2-8a > .kt-inside-inner-col,.kadence-column6676_80a5e2-8a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_80a5e2-8a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_80a5e2-8a > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_80a5e2-8a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_80a5e2-8a > .kt-inside-inner-col{background-color:#cff0f5;}.kadence-column6676_80a5e2-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_80a5e2-8a{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_80a5e2-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_80a5e2-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_80a5e2-8a inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-genesis-blocks-gb-container block_color_margin gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<h2 class=\"wp-block-heading\">20 altures diferents perqu\u00e8 tothom gaudeixi de la classe<\/h2>\n\n\n\n<p>Amb dues barres situades a 19 cent\u00edmetres de dist\u00e0ncia entre elles i 10 posicions ajustables, la Giselle \u00e9s una barra de gran versatilitat. L&#8217;altura de la Giselle es fixa amb facilitat, la qual cosa permet canvis r\u00e0pids per adaptar-se a diferents persones i exercicis. En qualsevol de les seves posicions, la Giselle mant\u00e9 la seva estabilitat i rendiment. <\/p>\n\n\n\n<p>El disseny exclusiu dels suports dobles de Dinamica Ballet distribueix la pressi\u00f3 que exerceix el ballar\u00ed sobre les barres de fusta. La gran estabilitat del conjunt permet a ballarines d&#8217;edats i al\u00e7ades diverses practicar alhora. Aquesta barra de ballet est\u00e0 disponible amb barres de fusta de 2 i 3 metres.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column6676_b713ac-e1 > .kt-inside-inner-col,.kadence-column6676_b713ac-e1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_b713ac-e1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_b713ac-e1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_b713ac-e1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_b713ac-e1 > .kt-inside-inner-col{background-image:url('https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_01_dinamica_ballet.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column6676_b713ac-e1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_b713ac-e1{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_b713ac-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_b713ac-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_b713ac-e1 inner-column-2 height_full\"><div class=\"kt-inside-inner-col\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id6676_5a72ce-41{margin-bottom:0px;}.kb-row-layout-id6676_5a72ce-41 > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id6676_5a72ce-41 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id6676_5a72ce-41 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6676_5a72ce-41 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6676_5a72ce-41 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6676_5a72ce-41 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6676_5a72ce-41 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom\">\n<style>.kadence-column6676_baed43-4d > .kt-inside-inner-col,.kadence-column6676_baed43-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_baed43-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_baed43-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_baed43-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_baed43-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_baed43-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_baed43-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_baed43-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_baed43-4d inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id6676_1056f7-80{margin-top:0px;}.kb-row-layout-id6676_1056f7-80 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id6676_1056f7-80 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id6676_1056f7-80 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:25px;grid-template-columns:minmax(0, calc(50% - ((40px * 1 )\/2)))minmax(0, calc(50% - ((40px * 1 )\/2)));}.kb-row-layout-id6676_1056f7-80 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6676_1056f7-80 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6676_1056f7-80 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6676_1056f7-80 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column6676_8cf23e-c3 > .kt-inside-inner-col,.kadence-column6676_8cf23e-c3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_8cf23e-c3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_8cf23e-c3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_8cf23e-c3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_8cf23e-c3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_8cf23e-c3{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_8cf23e-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_8cf23e-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_8cf23e-c3 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Base plana i base amb rodes; dues opcions per treure-hi el m\u00e0xim rendiment<\/h2>\n\n\n\n<p>La Giselle forma part de la nostra gamma de barres de ballet m\u00f2bils professionals. T&#8217;oferim dos tipus de bases d&#8217;acer: una amb dues rodes i un pes de 20 quilograms, i una altra base plana sense rodes de 10 quilograms cadascuna. La base amb rodes de goma d&#8217;alta densitat t&#8217;ofereix una gran estabilitat i et permetr\u00e0 traslladar la barra sense esfor\u00e7 inclinant el conjunt 45 graus des d&#8217;una posici\u00f3 central.<\/p>\n\n\n\n<p>La base plana est\u00e0 dissenyada perqu\u00e8 puguis moure la barra aixecant tot el conjunt sense recolzar-lo al terra. En tots dos casos, les bases estan equipades amb topalls de goma per evitar qualsevol dany o desperfecte al terra. Si necessites moure sovint la barra de ballet, et recomanem la base amb rodes; si l\u2019has de traslladar ocasionalment, o entre dues persones, la base plana et pot anar b\u00e9. El pes total del conjunt amb la base amb rodes equipada amb barra de fusta de 2 metres \u00e9s de 53 quilograms. El pes del conjunt amb bases planes sense rodes \u00e9s de 34 quilograms.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column6676_93bb39-54 > .kt-inside-inner-col,.kadence-column6676_93bb39-54 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_93bb39-54 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_93bb39-54 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_93bb39-54 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_93bb39-54 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_93bb39-54{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_93bb39-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_93bb39-54 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_93bb39-54 inner-column-2\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-getwid-images-slider has-arrows-none has-dots-none has-images-center has-fitted-images\"><div class=\"wp-block-getwid-images-slider__wrapper\" data-effect=\"fade\" data-slides-show=\"1\" data-slides-show-laptop=\"1\" data-slides-show-tablet=\"1\" data-slides-show-mobile=\"1\" data-slides-scroll=\"1\" data-autoplay=\"true\" data-autoplay-speed=\"2800\" data-infinite=\"true\" data-animation-speed=\"800\" data-center-mode=\"false\" data-variable-width=\"false\" data-arrows=\"none\" data-dots=\"none\" data-spacing=\"none\"><div class=\"wp-block-getwid-images-slider__item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1250\" height=\"886\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/avant_01_dinamica_ballet.jpg\" alt=\"Barra de ballet port\u00e1til AVANT\" data-id=\"1851\" data-link=\"https:\/\/www.dinamicaballet.com\/barra-de-ballet-simple-portatil-avant\/avant_01_dinamica_ballet\/\" data-original-link=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/avant_01_dinamica_ballet.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-1851\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/avant_01_dinamica_ballet.jpg 1250w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/avant_01_dinamica_ballet-300x213.jpg 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/avant_01_dinamica_ballet-1024x726.jpg 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/avant_01_dinamica_ballet-768x544.jpg 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/avant_01_dinamica_ballet-1200x851.jpg 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/avant_01_dinamica_ballet-600x425.jpg 600w\" sizes=\"auto, (max-width: 1250px) 100vw, 1250px\" \/><\/figure><\/div><div class=\"wp-block-getwid-images-slider__item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-scaled.jpg\" alt=\"\" data-id=\"2880\" data-link=\"https:\/\/www.dinamicaballet.com\/barra-de-ballet-portatil-doble-pina\/base-wheels-5\/\" data-original-link=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-scaled.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2880\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-scaled.jpg 2560w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-300x200.jpg 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-1024x683.jpg 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-768x512.jpg 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-1536x1024.jpg 1536w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-2048x1365.jpg 2048w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-600x400.jpg 600w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-1200x800.jpg 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-wheels-5-1400x933.jpg 1400w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/div><div class=\"wp-block-getwid-images-slider__item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-scaled.jpg\" alt=\"\" data-id=\"2877\" data-link=\"https:\/\/www.dinamicaballet.com\/barra-de-ballet-portatil-doble-pina\/base-flat-1\/\" data-original-link=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-scaled.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2877\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-scaled.jpg 2560w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-300x200.jpg 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-1024x683.jpg 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-768x512.jpg 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-1536x1024.jpg 1536w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-2048x1365.jpg 2048w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-600x400.jpg 600w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-1200x800.jpg 1200w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/06\/Base-flat-1-1400x933.jpg 1400w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id6676_ad955b-e9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6676_ad955b-e9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6676_ad955b-e9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id6676_ad955b-e9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6676_ad955b-e9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6676_ad955b-e9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6676_ad955b-e9 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column6676_1d19c8-fd > .kt-inside-inner-col,.kadence-column6676_1d19c8-fd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_1d19c8-fd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_1d19c8-fd > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_1d19c8-fd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_1d19c8-fd > .kt-inside-inner-col{background-image:url('https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/03\/giselle_03_dinamica_ballet.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column6676_1d19c8-fd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_1d19c8-fd{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_1d19c8-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_1d19c8-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_1d19c8-fd inner-column-1 height_full\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column6676_2cb40c-47 > .kt-inside-inner-col,.kadence-column6676_2cb40c-47 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_2cb40c-47 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_2cb40c-47 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_2cb40c-47 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_2cb40c-47 > .kt-inside-inner-col{background-color:#d9f4e7;}.kadence-column6676_2cb40c-47 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_2cb40c-47{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_2cb40c-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_2cb40c-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_2cb40c-47 inner-column-2\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-genesis-blocks-gb-container block_color_margin gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<h2 class=\"wp-block-heading\">Constru\u00efda amb els millors materials per treballar durant hores i hores<\/h2>\n\n\n\n<p>Les nostres barres de fusta de pi melis de boscos sostenibles s\u00f3n resistents i aporten una lleugera flexibilitat ideal per a exercicis avan\u00e7ats. La fusta perfectament polida i sense envernissar aporta un tacte agradable, una subjecci\u00f3 \u00f2ptima i una bellesa org\u00e0nica per gaudir al m\u00e0xim de la pr\u00e0ctica. Els suports subjecten amb total fermesa les barres de fusta sense la necessitat de fer-hi forats, la qual cosa assegura milers d&#8217;hores de pr\u00e0ctica i facilitat de muntatge.<\/p>\n\n\n\n<p>Hem fet estudis al Laboratori d&#8217;Elasticitat i Resist\u00e8ncia de Materials de la Universitat Polit\u00e8cnica de Barcelona que proven resist\u00e8ncies a forces de fins a gaireb\u00e9 400 quilograms. Les bases i els suports estan constru\u00efts amb acer de primera qualitat, amb un acabat en epoxi platejat que ofereix alta resist\u00e8ncia a cops i ratllades.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id6676_e37908-9f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6676_e37908-9f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6676_e37908-9f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id6676_e37908-9f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6676_e37908-9f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6676_e37908-9f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6676_e37908-9f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6676_9acfd2-5a > .kt-inside-inner-col,.kadence-column6676_9acfd2-5a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_9acfd2-5a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_9acfd2-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_9acfd2-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_9acfd2-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_9acfd2-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_9acfd2-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_9acfd2-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_9acfd2-5a inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-genesis-blocks-gb-container block_color_margin gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<h2 class=\"wp-block-heading\">3 suports, 4 i 5 metres, o fins i tot m\u00e9s!<\/h2>\n\n\n\n<p>La flexibilitat de l&#8217;espai \u00e9s vital. Les nostres barres m\u00f2bils per a \u00fas professional s&#8217;utilitzen en sales on es realitzen activitats diverses i on \u00e9s necessari adaptar l&#8217;espai constantment. <\/p>\n\n\n\n<p>Ara t&#8217;oferim la barra de ballet Giselle en conjunts de 4 i 5 metres, amb 3 suports, per a que diverses persones puguin realitzar la pr\u00e0ctica en la mateixa barra. A m\u00e9s, podr\u00e0s continuar tenint total llibertat a l&#8217;aula gr\u00e0cies al seu c\u00f2mode despla\u00e7ament. Trobar\u00e0s la Giselle amb aquesta innovadora configuraci\u00f3 amb tots dos tipus de base, amb rodes i planes.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column6676_cfa785-8a > .kt-inside-inner-col,.kadence-column6676_cfa785-8a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_cfa785-8a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_cfa785-8a > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_cfa785-8a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_cfa785-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_cfa785-8a{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_cfa785-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_cfa785-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_cfa785-8a inner-column-2\"><div class=\"kt-inside-inner-col\">\n<div style=\"height:162px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2023\/09\/Dinamica-Ballet-giselle-3-supports-1024x683.png\" alt=\"Barra de ballet doble d'al\u00e7ada regulable amb 3 suports\" class=\"wp-image-74980\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2023\/09\/Dinamica-Ballet-giselle-3-supports-1024x683.png 1024w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2023\/09\/Dinamica-Ballet-giselle-3-supports-300x200.png 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2023\/09\/Dinamica-Ballet-giselle-3-supports-768x512.png 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2023\/09\/Dinamica-Ballet-giselle-3-supports-500x333.png 500w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2023\/09\/Dinamica-Ballet-giselle-3-supports-800x533.png 800w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2023\/09\/Dinamica-Ballet-giselle-3-supports-600x400.png 600w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2023\/09\/Dinamica-Ballet-giselle-3-supports.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/HhkzgvJWXHY?&amp;autoplay=1&amp;controls=0&amp;playlist=HhkzgvJWXHY&amp;loop=1&amp;mute=1&amp;showinfo=0&amp;modestbranding=1\" title=\"Giselle\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e9s sobre aquest producte<\/h2>\n\n\n<style>.kt-accordion-id6676_ba2dd5-78 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id6676_ba2dd5-78 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;background:#ffffff;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid #eeeeee;border-left-color:#eeeeee;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;font-size:18px;line-height:24px;color:#444444;padding-top:14px;padding-right:16px;padding-bottom:14px;padding-left:16px;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id6676_ba2dd5-78 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#ffffff;border-top-color:#d4d4d4;border-top-style:solid;border-right-color:#d4d4d4;border-right-style:solid;border-bottom:1px solid #d4d4d4;border-left-color:#d4d4d4;border-left-style:solid;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id6676_ba2dd5-78 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#444444;background:#ffffff;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid #eeeeee;border-left-color:#0e9cd1;border-left-style:solid;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6676_ba2dd5-78:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}@media all and (max-width: 1024px){.kt-accordion-id6676_ba2dd5-78 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid #eeeeee;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id6676_ba2dd5-78 .kt-blocks-accordion-header:focus-visible{border-top-color:#d4d4d4;border-top-style:solid;border-right-color:#d4d4d4;border-right-style:solid;border-bottom:1px solid #d4d4d4;border-left-color:#d4d4d4;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id6676_ba2dd5-78 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid #eeeeee;border-left-color:#0e9cd1;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id6676_ba2dd5-78 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id6676_ba2dd5-78 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id6676_ba2dd5-78 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid #eeeeee;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id6676_ba2dd5-78 .kt-blocks-accordion-header:focus-visible{border-top-color:#d4d4d4;border-top-style:solid;border-right-color:#d4d4d4;border-right-style:solid;border-bottom:1px solid #d4d4d4;border-left-color:#d4d4d4;border-left-style:solid;}.kt-accordion-id6676_ba2dd5-78 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id6676_ba2dd5-78 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid #eeeeee;border-left-color:#0e9cd1;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone block_accordion\"><div class=\"kt-accordion-wrap kt-accordion-id6676_ba2dd5-78 kt-accordion-has-2-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane6676_11dd84-2c\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_bookOpen kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M2 3h6a4 4 0 0 1 4 4v14a3 3 0 0 0-3-3H2z\"\/><path d=\"M22 3h-6a4 4 0 0 0-4 4v14a3 3 0 0 1 3-3h7z\"\/><\/svg><\/span><span class=\"kt-blocks-accordion-title\">Fitxa t\u00e8cnica<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/05\/FT-GISELLE-0421-3.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarregar Fitxa<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Codi SKU:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>150 cm amb rodes: 30591923&nbsp;<\/li>\n\n\n\n<li>200 cm amb rodes: 30591922&nbsp;<\/li>\n\n\n\n<li>300 cm amb rodes: 30591921<\/li>\n\n\n\n<li>150 cm sense rodes: 30592023&nbsp;<\/li>\n\n\n\n<li>200 cm sense rodes: 30592022&nbsp;<\/li>\n\n\n\n<li>300 cm sense rodes: 30592021<\/li>\n<\/ul>\n\n\n\n<p>&nbsp;<strong>Materials:<\/strong> Base d&#8217;acer de color gris martel\u00e9. Columna i suport d&#8217;acer color plata.&nbsp;<\/p>\n\n\n\n<p><strong>Pes:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L 150 cm amb rodes: 53,0 kg&nbsp;<\/li>\n\n\n\n<li>L 200 cm amb rodes: 54,5 kg&nbsp;<\/li>\n\n\n\n<li>L 300 cm amb rodes: 55,0 kg<\/li>\n\n\n\n<li>L 150 cm sense rodes: 34,0 kg&nbsp;<\/li>\n\n\n\n<li>L 200 cm sense rodes: 35,0 kg&nbsp;<\/li>\n\n\n\n<li>L 300 cm sense rodes: 36,0 kg<\/li>\n<\/ul>\n\n\n\n<p><strong>Mesures<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Base amb rodes: 320mm x 395mm x 20mm<\/li>\n\n\n\n<li>Base sense rodes: 320mm x 395mm x 10mm<\/li>\n\n\n\n<li>Di\u00e0metre tub superior : \u00d8 42mm<\/li>\n\n\n\n<li>Di\u00e0metre tub inferior: \u00d8 50mm<\/li>\n\n\n\n<li>Dist\u00e0ncia entre barres de fusta: 19 cm<\/li>\n<\/ul>\n\n\n\n<p><strong>Barra de fusta<\/strong>:&nbsp;2 barres de Pi Melis de \u00d8 40mm de 150cm, 200cm o 300cm<\/p>\n\n\n\n<p><strong>Regulador d&#8217;altura:<\/strong> <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>10 posicions<\/li>\n\n\n\n<li>Altura m\u00e0xima de la barra superior: 120,5 cm<\/li>\n\n\n\n<li>Altura m\u00e0xima de la barra inferior: 120,5 cm<\/li>\n\n\n\n<li>Altura m\u00ednima  de la barra superior: 93,5 cm<\/li>\n\n\n\n<li>Altura m\u00ednima de la barra inferior: 70,5 cm<\/li>\n\n\n\n<li>Mecanisme de fixaci\u00f3 de PVC i \u00d8 Metric 8<\/li>\n<\/ul>\n\n\n\n<p><strong>Inclou:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>DIN 7991 M-12 x 50 mm <strong>x2<\/strong><\/li>\n\n\n\n<li>DIN 7991 M-6 \u00d7 14mm A2 <strong>x16<\/strong><\/li>\n\n\n\n<li>Allen 8mm x1 | Allen 4mm <strong>x1<\/strong><\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"1129\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/05\/FT_GISELLE.png\" alt=\"Barra de ballet profesional doble de altura regulable Giselle\" class=\"wp-image-2574\" style=\"width:331px;height:565px\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/05\/FT_GISELLE.png 661w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/05\/FT_GISELLE-176x300.png 176w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/05\/FT_GISELLE-600x1025.png 600w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/05\/FT_GISELLE-300x512.png 300w\" sizes=\"auto, (max-width: 661px) 100vw, 661px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/05\/FT-GISELLE-0421-3.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarregar Fitxa<\/a><\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane6676_e65316-c5\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_settings kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"3\"\/><path d=\"M19.4 15a1.65 1.65 0 0 0 .33 1.82l.06.06a2 2 0 0 1 0 2.83 2 2 0 0 1-2.83 0l-.06-.06a1.65 1.65 0 0 0-1.82-.33 1.65 1.65 0 0 0-1 1.51V21a2 2 0 0 1-2 2 2 2 0 0 1-2-2v-.09A1.65 1.65 0 0 0 9 19.4a1.65 1.65 0 0 0-1.82.33l-.06.06a2 2 0 0 1-2.83 0 2 2 0 0 1 0-2.83l.06-.06a1.65 1.65 0 0 0 .33-1.82 1.65 1.65 0 0 0-1.51-1H3a2 2 0 0 1-2-2 2 2 0 0 1 2-2h.09A1.65 1.65 0 0 0 4.6 9a1.65 1.65 0 0 0-.33-1.82l-.06-.06a2 2 0 0 1 0-2.83 2 2 0 0 1 2.83 0l.06.06a1.65 1.65 0 0 0 1.82.33H9a1.65 1.65 0 0 0 1-1.51V3a2 2 0 0 1 2-2 2 2 0 0 1 2 2v.09a1.65 1.65 0 0 0 1 1.51 1.65 1.65 0 0 0 1.82-.33l.06-.06a2 2 0 0 1 2.83 0 2 2 0 0 1 0 2.83l-.06.06a1.65 1.65 0 0 0-.33 1.82V9a1.65 1.65 0 0 0 1.51 1H21a2 2 0 0 1 2 2 2 2 0 0 1-2 2h-.09a1.65 1.65 0 0 0-1.51 1z\"\/><\/svg><\/span><span class=\"kt-blocks-accordion-title\">Muntatge<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/07\/Instruccions-Giselle.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarregar instruccions<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Instrucciones de montaje de la barra de ballet doble regulable Giselle\" width=\"905\" height=\"509\" src=\"https:\/\/www.youtube.com\/embed\/vZ74x63tRdk?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.dinamicaballet.com\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Tens 6 elements: 2 bases, 2 columnes i 2 barres de fusta. Primer cal muntar les columnes sobre les bases (A) i a continuaci\u00f3 fixar les barres de fusta en els suports (B). El mecanisme per regular l\u2019al\u00e7ada (C)&nbsp; es lliura ja muntat. El muntatge de la base amb rodes i la base sense rodes \u00e9s id\u00e8ntic.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"193\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_01a.png\" alt=\"Instrucciones Giselle\" class=\"wp-image-2308\" style=\"width:164px;height:111px\"\/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"679\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_01.png\" alt=\"Instrucciones Giselle\" class=\"wp-image-2307\" style=\"width:355px;height:411px\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_01.png 588w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_01-260x300.png 260w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_01-300x346.png 300w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>1. Inclina una de les columnes i col\u00b7loca-la sobre l\u2019orifici central d\u2019una base. Des de la part anterior de la base, la que quedar\u00e0 recolzada a terra i t\u00e9 les proteccions, introdueix el cargol gran i uneix-lo a la columna a trav\u00e9s de la base. Colla\u2019l amb for\u00e7a amb la clau Allen fins que la columna quedi perfectament fixada a la base. Repeteix el proc\u00e9s amb la segona columna.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"242\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_04.png\" alt=\"Instrucciones Giselle\" class=\"wp-image-2311\" style=\"width:734px;height:207px\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_04.png 860w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_04-300x84.png 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_04-768x216.png 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_04-600x169.png 600w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>2. Posa dempeus les dues columnes i situa-les una al costat de l\u2019altra. Afluixa els cargols de la platina inferior i superior d\u2019ambd\u00f3s suports i introdueix la barra de fusta entre les dues platines. Recomanem que la barra de fusta sobresurti entre 20 i 30 cent\u00edmetres de la part exterior del suport. Ajusta amb la clau allen tots els cargols assegurant-te que la barra de fusta queda perfectament fixada.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"866\" height=\"464\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_02.png\" alt=\"Instrucciones Giselle\" class=\"wp-image-2309\" style=\"width:537px;height:288px\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_02.png 866w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_02-300x161.png 300w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_02-768x411.png 768w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_02-600x321.png 600w\" sizes=\"auto, (max-width: 866px) 100vw, 866px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Per moure el conjunt sense rodes, situa\u2019t a la part central de la barra de fusta i aixeca-la completament del terra amb les dues mans. No arrosseguis les bases, aix\u00ed evitarem fer malb\u00e9 els taps de goma i ratllar el terra. Per traslladar el conjunt amb rodes, situa\u2019t a la part central de la barra i inclina el conjunt 45\u00b0 fins que les rodes es recolzin completament en el terra. Estira-la amb suavitat intentant que les dues columnes es desplacin simult\u00e0niament, aix\u00ed evitar\u00e0s crear tensi\u00f3 sobre la barra de fusta.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"570\" height=\"242\" src=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_03.png\" alt=\"Instrucciones Giselle\" class=\"wp-image-2306\" style=\"width:455px;height:193px\" srcset=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_03.png 570w, https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/04\/instruccion_giselle_03-300x127.png 300w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2021\/07\/Instruccions-Giselle.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarregar instruccions<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>.kb-row-layout-id6676_e4b443-2c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6676_e4b443-2c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6676_e4b443-2c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(70% - ((var(--global-kb-gap-sm, 1rem) * 1 )\/2)))minmax(0, calc(30% - ((var(--global-kb-gap-sm, 1rem) * 1 )\/2)));}.kb-row-layout-id6676_e4b443-2c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6676_e4b443-2c > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6676_e4b443-2c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6676_e4b443-2c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6676_3d53a6-3e > .kt-inside-inner-col,.kadence-column6676_3d53a6-3e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_3d53a6-3e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_3d53a6-3e > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_3d53a6-3e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_3d53a6-3e > .kt-inside-inner-col{background-color:#fff2d5;}.kadence-column6676_3d53a6-3e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_3d53a6-3e{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_3d53a6-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_3d53a6-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_3d53a6-3e inner-column-1 box_more_information\"><div class=\"kt-inside-inner-col\">\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f10226-o1\" lang=\"ca\" dir=\"ltr\" data-wpcf7-id=\"10226\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/pages\/6676#wpcf7-f10226-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulari de contacte\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"10226\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ca\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f10226-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<h3>Volem ajudar-te a fer realitat el teu projecte\n<\/h3>\n<p>Si tens qualsevol dubte o necessites un pressupost personalitzat, estarem contents d\u2019ajudar-te.\n<\/p>\n<p>\t\t<div id=\"cf7md-form\" class=\"cf7md-form\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t<div class=\"mdc-layout-grid__inner\">\n\t\t\t\t\t\t\t\t\t\t\n<\/p>\n<p><strong>Dades de contacte<\/strong>\n<\/p>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-4-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"nombreidea\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Persona de contacte<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-4-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"emailidea\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Correu electr\u00f2nic<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-4-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telephone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telephone\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Tel\u00e8fon<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<p><strong>Dades professionals<\/strong>\n<\/p>\n\t\t<div class=\"cf7md-item cf7md-select mdc-layout-grid__cell mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-340\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-340\"><option value=\"\">&#8212;Trieu una opci\u00f3&#8212;<\/option><option value=\"Escola o companyia de dansa\">Escola o companyia de dansa<\/option><option value=\"Conservatori \/ teatre \/ \u00f2pera\">Conservatori \/ teatre \/ \u00f2pera<\/option><option value=\"Centre esportiu\">Centre esportiu<\/option><option value=\"Estudi de Ioga \/ Pilates\">Estudi de Ioga \/ Pilates<\/option><option value=\"Arquitecte \/ constructora \/ interiorista\">Arquitecte \/ constructora \/ interiorista<\/option><option value=\"Centre m\u00e8dic \/ rehabilitaci\u00f3\">Centre m\u00e8dic \/ rehabilitaci\u00f3<\/option><option value=\"Cliente particular \/ Uso dom\u00e9stico\">Cliente particular \/ Uso dom\u00e9stico<\/option><option value=\"Altres\">Altres<\/option><\/select><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-select-html\">\n\t\t\t\t<div class=\"mdc-select  mdc-select--box\">\n\t\t\t\t\t\t\n\t\t\t\t\t<i class=\"mdc-select__dropdown-icon\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Des d'on ens contactes?<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"organisation\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"organisation\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Nom d'empresa<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"city\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Poblaci\u00f3<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-2-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"postal\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"postal\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">CP<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-4-desktop mdc-layout-grid__cell--span-4-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"country-text\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-countrytext wpcf7-text wpcf7-validates-as-countrytext\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"country-text\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\"><\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"countrycodeidea\" value=\"ES\" type=\"hidden\" name=\"country\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"yournameidea\" value=\"\" type=\"hidden\" name=\"your-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"youremailidea\" value=\"\" type=\"hidden\" name=\"your-email\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"yoursubjectidea\" value=\"\" type=\"hidden\" name=\"your-subject\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"yourmessageidea\" value=\"\" type=\"hidden\" name=\"your-message\" \/>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"subjectidea\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"subject\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field \">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Assumpte<\/label>\n\t\t\t\t\t\t<div class=\"mdc-line-ripple\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\n\t\t<div class=\"cf7md-item cf7md-textarea mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone cf7md-textarea-autosize\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"messageidea\" aria-required=\"true\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--textarea\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">En qu\u00e8 et podem ajudar?<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-accept cf7md-is-wpcf7v5 mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-878\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-878\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span><br \/>\n\t\t\t<label class=\"cf7md-accept-label\">He llegit i accepto <a href='https:\/\/www.dinamicaballet.com\/aviso-legal\/'>Av\u00eds legal i la pol\u00edtica de privacitat<\/a><\/label>\n\t\t\t<div style=\"display: none;\" class=\"cf7md-checkbox-html\">\n\t\t\t\t<div class=\"mdc-checkbox__background\">\n\t\t\t\t\t<svg class=\"mdc-checkbox__checkmark\" viewBox=\"0 0 24 24\">\n\t\t\t\t\t\t<path class=\"mdc-checkbox__checkmark-path\" fill=\"none\" d=\"M1.73,12.91 8.1,19.28 22.79,4.59\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t\t<div class=\"mdc-checkbox__mixedmark\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\" data-button-style=\"raised\">\n\t\t\t<br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/><br \/>\n\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column6676_f94adb-98 > .kt-inside-inner-col,.kadence-column6676_f94adb-98 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6676_f94adb-98 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6676_f94adb-98 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6676_f94adb-98 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6676_f94adb-98 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6676_f94adb-98{position:relative;}@media all and (max-width: 1024px){.kadence-column6676_f94adb-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6676_f94adb-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6676_f94adb-98 inner-column-2\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button button_blue_02 ek-w-full\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.dinamicaballet.com\/ca\/producto\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/\">Comprar a <strong>botiga online<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-container box_menu_more_product gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<h4 class=\"wp-block-heading\">Barres de ballet m\u00f2bils<\/h4>\n\n\n<ul id=\"menu-barras-moviles-catala\" class=\"menu menu_sidebar_product\"><li id=\"menu-item-7476\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7476\"><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-iniciacio-prima\/\">Iniciaci\u00f3 Prima<\/a><\/li>\n<li id=\"menu-item-7477\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7477\"><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-diniciacio-daltura-regulable-juliette\/\">Iniciaci\u00f3 regulable Juliette<\/a><\/li>\n<li id=\"menu-item-7478\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7478\"><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-professional-avant\/\">Una barra Avant<\/a><\/li>\n<li id=\"menu-item-7479\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7479\"><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-professional-daltura-regulable-isa\/\">Regulable Isa<\/a><\/li>\n<li id=\"menu-item-7480\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7480\"><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-professional-mobil-doble-pina\/\">Doble Pina<\/a><\/li>\n<li id=\"menu-item-7481\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7481\"><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/\">Doble regulable Giselle<\/a><\/li>\n<li id=\"menu-item-7482\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7482\"><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-premium-maurice\/\">Pr\u00e8mium doble Maurice<\/a><\/li>\n<li id=\"menu-item-7483\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7483\"><a href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-doble-premium-daltura-regulable-royale\/\">Pr\u00e8mium doble regulable Royale<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Giselle \u00e9s una barra de ballet professional amb suports per a dues barres de fusta i mecanisme de regulaci\u00f3 d&#8217;altura<\/p>\n","protected":false},"author":6,"featured_media":7172,"parent":0,"menu_order":302,"comment_status":"closed","ping_status":"closed","template":"templates\/template-builder.php","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":4,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"class_list":["post-6676","page","type-page","status-publish","has-post-thumbnail","hentry","post","with-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barra de ballet professional m\u00f2bil doble d&#039;altura regulable | Dinamica Ballet<\/title>\n<meta name=\"description\" content=\"La Giselle \u00e9s una barra de ballet professional amb suports per a dues barres de fusta i mecanisme de regulaci\u00f3 d&#039;altura\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barra de ballet professional m\u00f2bil doble d&#039;altura regulable | Dinamica Ballet\" \/>\n<meta property=\"og:description\" content=\"La Giselle \u00e9s una barra de ballet professional amb suports per a dues barres de fusta i mecanisme de regulaci\u00f3 d&#039;altura\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/\" \/>\n<meta property=\"og:site_name\" content=\"Dinamica Ballet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dinamicaballet\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T11:10:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2020\/12\/dinamica_ballet_shop_giselle_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\\\/\",\"url\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\\\/\",\"name\":\"Barra de ballet professional m\u00f2bil doble d'altura regulable | Dinamica Ballet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dinamicaballet.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/dinamica_ballet_shop_giselle_01.jpg\",\"datePublished\":\"2021-08-25T17:28:17+00:00\",\"dateModified\":\"2025-11-06T11:10:53+00:00\",\"description\":\"La Giselle \u00e9s una barra de ballet professional amb suports per a dues barres de fusta i mecanisme de regulaci\u00f3 d'altura\",\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dinamicaballet.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/dinamica_ballet_shop_giselle_01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dinamicaballet.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/dinamica_ballet_shop_giselle_01.jpg\",\"width\":600,\"height\":800,\"caption\":\"Barra de ballet m\u00f2bil doble d\u2019altura regulable Giselle\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/\",\"name\":\"Dinamica Ballet\",\"description\":\"Especialistas en barras de ballet y espejos para la danza\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/#organization\",\"name\":\"Dinamica Ballet\",\"url\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dinamicaballet.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_dinamica_ballet.svg\",\"contentUrl\":\"https:\\\/\\\/www.dinamicaballet.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_dinamica_ballet.svg\",\"width\":284,\"height\":51,\"caption\":\"Dinamica Ballet\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dinamicaballet.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dinamicaballet\",\"https:\\\/\\\/www.instagram.com\\\/dinamicaballet\\\/\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/dinamica-ballet\",\"https:\\\/\\\/www.pinterest.com\\\/DinamicaBallet\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barra de ballet professional m\u00f2bil doble d'altura regulable | Dinamica Ballet","description":"La Giselle \u00e9s una barra de ballet professional amb suports per a dues barres de fusta i mecanisme de regulaci\u00f3 d'altura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/","og_locale":"ca_ES","og_type":"article","og_title":"Barra de ballet professional m\u00f2bil doble d'altura regulable | Dinamica Ballet","og_description":"La Giselle \u00e9s una barra de ballet professional amb suports per a dues barres de fusta i mecanisme de regulaci\u00f3 d'altura","og_url":"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/","og_site_name":"Dinamica Ballet","article_publisher":"https:\/\/www.facebook.com\/dinamicaballet","article_modified_time":"2025-11-06T11:10:53+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2020\/12\/dinamica_ballet_shop_giselle_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"15 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/","url":"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/","name":"Barra de ballet professional m\u00f2bil doble d'altura regulable | Dinamica Ballet","isPartOf":{"@id":"https:\/\/www.dinamicaballet.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/#primaryimage"},"image":{"@id":"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2020\/12\/dinamica_ballet_shop_giselle_01.jpg","datePublished":"2021-08-25T17:28:17+00:00","dateModified":"2025-11-06T11:10:53+00:00","description":"La Giselle \u00e9s una barra de ballet professional amb suports per a dues barres de fusta i mecanisme de regulaci\u00f3 d'altura","inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.dinamicaballet.com\/ca\/barra-de-ballet-mobil-doble-daltura-regulable-giselle\/#primaryimage","url":"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2020\/12\/dinamica_ballet_shop_giselle_01.jpg","contentUrl":"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2020\/12\/dinamica_ballet_shop_giselle_01.jpg","width":600,"height":800,"caption":"Barra de ballet m\u00f2bil doble d\u2019altura regulable Giselle"},{"@type":"WebSite","@id":"https:\/\/www.dinamicaballet.com\/ca\/#website","url":"https:\/\/www.dinamicaballet.com\/ca\/","name":"Dinamica Ballet","description":"Especialistas en barras de ballet y espejos para la danza","publisher":{"@id":"https:\/\/www.dinamicaballet.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dinamicaballet.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.dinamicaballet.com\/ca\/#organization","name":"Dinamica Ballet","url":"https:\/\/www.dinamicaballet.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.dinamicaballet.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2022\/03\/logo_dinamica_ballet.svg","contentUrl":"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2022\/03\/logo_dinamica_ballet.svg","width":284,"height":51,"caption":"Dinamica Ballet"},"image":{"@id":"https:\/\/www.dinamicaballet.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dinamicaballet","https:\/\/www.instagram.com\/dinamicaballet\/","http:\/\/www.linkedin.com\/company\/dinamica-ballet","https:\/\/www.pinterest.com\/DinamicaBallet\/"]}]}},"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2020\/12\/dinamica_ballet_shop_giselle_01.jpg",600,800,false],"author_info":{"display_name":false,"author_link":"https:\/\/www.dinamicaballet.com\/ca\/author\/carles\/"},"comment_info":0,"featured_image_src":"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2020\/12\/dinamica_ballet_shop_giselle_01-600x400.jpg","featured_image_src_square":"https:\/\/www.dinamicaballet.com\/wp-content\/uploads\/2020\/12\/dinamica_ballet_shop_giselle_01-600x600.jpg","_links":{"self":[{"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/pages\/6676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/comments?post=6676"}],"version-history":[{"count":22,"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/pages\/6676\/revisions"}],"predecessor-version":[{"id":105235,"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/pages\/6676\/revisions\/105235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/media\/7172"}],"wp:attachment":[{"href":"https:\/\/www.dinamicaballet.com\/ca\/wp-json\/wp\/v2\/media?parent=6676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}